{"id":1163,"date":"2024-01-15T12:55:22","date_gmt":"2024-01-15T11:55:22","guid":{"rendered":"https:\/\/luiss94.sg-host.com\/proyecto\/a-home-on-a-hillside\/"},"modified":"2024-01-15T12:55:24","modified_gmt":"2024-01-15T11:55:24","slug":"a-home-on-a-hillside","status":"publish","type":"proyecto","link":"https:\/\/uniquehouses.es\/en\/proyecto\/a-home-on-a-hillside\/","title":{"rendered":"A home on a hillside"},"content":{"rendered":"\n<section class=\"wp-block-uagb-container hero hero-proyecto hero-header-transparente uagb-block-f71ce813 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/section>\n\n\n\n<div class=\"wp-block-uagb-container bloque bloque-sub-hero texto-proyecto aparecer-subiendo uagb-block-d06260ad default uagb-is-root-container\">\n<h1 class=\"wp-block-heading\">A HOME ON A HILLSIDE<\/h1>\n\n\n\n<p>In this case, the challenge was to build a single-family home with white concrete walls on a very steep plot. Access to the home was created via the upper floor, where the garage and the main entrance were built.<\/p>\n\n\n\n<p>To provide access to the common area (living room \/ dining room \/ kitchen), a large, two-meter-wide staircase was built. Said staircase acquires great protagonism as it spans two flights and features glass overlooking the garden and pool area, with spectacular views of a forest facing south.<\/p>\n\n\n\n<p>To ensure the home\u2019s privacy in terms of the adjacent plot, a large false fa\u00e7ade with white concrete horizontal sections was installed. On the outside, all retaining walls were built with white gabion stone. All outside flooring is polished concrete with epoxy paint to enhance the landscape.<\/p>\n\n\n\n<p>The inside of the home was done in a very contemporary style, yet it still features many traditional crafty elements as well. For example, oak plates were installed to be used as sink countertops and contrast with the gray walls, the fireplace was done in iron, and furnishings with an industrial feel were chosen.<\/p>\n\n\n\n<p>As in all our projects, special attention was paid to energy efficiency. In this case, the home features radiant floor heating and cooling, aerothermics, and forced ventilation. En este caso, la climatizaci\u00f3n se realiz\u00f3 con suelo radiante fr\u00edo-calor, aerotermia y ventilaci\u00f3n forzada.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5f252c3f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped galeria galeria-proyecto wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg\" data-lbwps-width=\"875\" data-lbwps-height=\"1400\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-340x544.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"1400\" data-id=\"564\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg\" alt=\"Unique Houses Casa Ladera Ventanal\" class=\"wp-image-564\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg 875w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-480x768.jpg 480w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-576x921.jpg 576w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-340x544.jpg 340w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-768x1229.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><\/a><figcaption>Unique Houses Casa Ladera Ventanal<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina3.jpg\" data-lbwps-width=\"1400\" data-lbwps-height=\"875\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina3-544x340.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"875\" data-id=\"558\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina3.jpg\" alt=\"Unique Houses Casa Ladera Piscina3\" class=\"wp-image-558\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina3.jpg 1400w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina3-768x480.jpg 768w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina3-921x576.jpg 921w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina3-544x340.jpg 544w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><figcaption>Unique Houses Casa Ladera Piscina3<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina2.jpg\" data-lbwps-width=\"1400\" data-lbwps-height=\"875\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina2-544x340.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"875\" data-id=\"555\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina2.jpg\" alt=\"Unique Houses Casa Ladera Piscina2\" class=\"wp-image-555\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina2.jpg 1400w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina2-768x480.jpg 768w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina2-921x576.jpg 921w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina2-544x340.jpg 544w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><figcaption>Unique Houses Casa Ladera Piscina2<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina.jpg\" data-lbwps-width=\"875\" data-lbwps-height=\"1400\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina-340x544.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"1400\" data-id=\"552\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina.jpg\" alt=\"Unique Houses Casa Ladera Piscina\" class=\"wp-image-552\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina.jpg 875w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina-480x768.jpg 480w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina-576x921.jpg 576w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina-340x544.jpg 340w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-piscina-768x1229.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><\/a><figcaption>Unique Houses Casa Ladera Piscina<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-hormigon.jpg\" data-lbwps-width=\"1400\" data-lbwps-height=\"875\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-hormigon-544x340.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"875\" data-id=\"549\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-hormigon.jpg\" alt=\"Unique Houses Casa Ladera Paneles Hormigon\" class=\"wp-image-549\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-hormigon.jpg 1400w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-hormigon-768x480.jpg 768w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-hormigon-921x576.jpg 921w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-hormigon-544x340.jpg 544w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><figcaption>Unique Houses Casa Ladera Paneles Hormigon<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2.jpg\" data-lbwps-width=\"875\" data-lbwps-height=\"1400\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2-340x544.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"1400\" data-id=\"546\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2.jpg\" alt=\"Unique Houses Casa Ladera Paneles De Hormigon 2\" class=\"wp-image-546\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2.jpg 875w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2-480x768.jpg 480w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2-576x921.jpg 576w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2-340x544.jpg 340w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-paneles-de-hormigon-2-768x1229.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><\/a><figcaption>Unique Houses Casa Ladera Paneles De Hormigon 2<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-lateral.jpg\" data-lbwps-width=\"1400\" data-lbwps-height=\"875\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-lateral-544x340.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"875\" data-id=\"543\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-lateral.jpg\" alt=\"Unique Houses Casa Ladera Lateral\" class=\"wp-image-543\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-lateral.jpg 1400w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-lateral-768x480.jpg 768w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-lateral-921x576.jpg 921w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-lateral-544x340.jpg 544w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><figcaption>Unique Houses Casa Ladera Lateral<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada.jpg\" data-lbwps-width=\"1400\" data-lbwps-height=\"875\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-544x340.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"875\" data-id=\"540\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada.jpg\" alt=\"Unique Houses Casa Ladera Fachada\" class=\"wp-image-540\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada.jpg 1400w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-768x480.jpg 768w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-921x576.jpg 921w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-544x340.jpg 544w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><figcaption>Unique Houses Casa Ladera Fachada<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-posterior.jpg\" data-lbwps-width=\"1400\" data-lbwps-height=\"875\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-posterior-544x340.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"875\" data-id=\"537\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-posterior.jpg\" alt=\"Unique Houses Casa Ladera Fachada Posterior\" class=\"wp-image-537\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-posterior.jpg 1400w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-posterior-768x480.jpg 768w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-posterior-921x576.jpg 921w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-fachada-posterior-544x340.jpg 544w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><figcaption>Unique Houses Casa Ladera Fachada Posterior<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera.jpg\" data-lbwps-width=\"875\" data-lbwps-height=\"1400\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera-340x544.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"1400\" data-id=\"534\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera.jpg\" alt=\"Unique Houses Casa Ladera Escalera\" class=\"wp-image-534\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera.jpg 875w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera-480x768.jpg 480w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera-576x921.jpg 576w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera-340x544.jpg 340w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-escalera-768x1229.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><\/a><figcaption>Unique Houses Casa Ladera Escalera<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-entrada.jpg\" data-lbwps-width=\"1400\" data-lbwps-height=\"875\" data-lbwps-srcsmall=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-entrada-544x340.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"875\" data-id=\"531\" src=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-entrada.jpg\" alt=\"Unique Houses Casa Ladera Entrada\" class=\"wp-image-531\" srcset=\"https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-entrada.jpg 1400w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-entrada-768x480.jpg 768w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-entrada-921x576.jpg 921w, https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-entrada-544x340.jpg 544w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/a><figcaption>Unique Houses Casa Ladera Entrada<\/figcaption><\/figure>\n<\/figure>\n<\/div><\/div>\n","protected":false},"featured_media":565,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1163","proyecto","type-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg",875,1400,false],"thumbnail":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-340x544.jpg",340,544,true],"medium":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-480x768.jpg",480,768,true],"medium_large":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-768x1229.jpg",768,1229,true],"large":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal-576x921.jpg",576,921,true],"1536x1536":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg",875,1400,false],"2048x2048":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg",875,1400,false],"gform-image-choice-sm":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg",188,300,false],"gform-image-choice-md":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg",250,400,false],"gform-image-choice-lg":["https:\/\/uniquehouses.es\/wp-content\/uploads\/Unique-houses-casa-ladera-ventanal.jpg",375,600,false]},"uagb_author_info":{"display_name":"luigichereguini","author_link":"https:\/\/uniquehouses.es\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A HOME ON A HILLSIDE In this case, the challenge was to build a single-family home with white concrete walls on a very steep plot. Access to the home was created via the upper floor, where the garage and the main entrance were built. To provide access to the common area (living room \/ dining&hellip;","_links":{"self":[{"href":"https:\/\/uniquehouses.es\/en\/wp-json\/wp\/v2\/proyecto\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniquehouses.es\/en\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/uniquehouses.es\/en\/wp-json\/wp\/v2\/types\/proyecto"}],"version-history":[{"count":0,"href":"https:\/\/uniquehouses.es\/en\/wp-json\/wp\/v2\/proyecto\/1163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniquehouses.es\/en\/wp-json\/wp\/v2\/media\/565"}],"wp:attachment":[{"href":"https:\/\/uniquehouses.es\/en\/wp-json\/wp\/v2\/media?parent=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}